{"id":2421,"date":"2017-02-19T00:00:00","date_gmt":"2017-02-18T23:00:00","guid":{"rendered":"https:\/\/new.bulldozair.com\/sin-categorizar\/crea-informes\/"},"modified":"2017-02-19T00:00:00","modified_gmt":"2017-02-18T23:00:00","slug":"crea-informes","status":"publish","type":"post","link":"https:\/\/www.bulldozair.com\/es\/centro-ayuda\/sinc-busca-reporte\/crea-informes\/","title":{"rendered":"Crea informes"},"content":{"rendered":"<p>Los informes son una herramienta informativa muy importante para ti y todos los dem\u00e1s colaboradores del proyecto, ya que te permiten resumir y mostrar de manera organizada toda la informaci\u00f3n de tus notas que consideres relevante. Existen tres tipos diferentes de informes: Resumen, Completo y CSV para Excel. Puedes escoger la informaci\u00f3n presente dentro de tu informe y organizarla por zonas, etiquetas o participantes, adem\u00e1s de poder organizarla por orden alfab\u00e9tico, fecha de creaci\u00f3n o n\u00famero de nota.<\/p>\n<div id=\"tabs\">\n<ul>\n<li><a href=\"#tabs-1\">Android<\/a><\/li>\n<li><a href=\"#tabs-2\">iOS<\/a><\/li>\n<li><a href=\"#tabs-3\">Web<\/a><\/li>\n<\/ul>\n<div id=\"tabs-1\">\n<ol>\n<li>Seleccione el proyecto que contiene la nota desde la que se generar\u00e1 el informe<\/li>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bulldozair.com\/wp-content\/uploads\/2020\/09\/sup-create-reports-1-android-en.png\" alt=\"\" width=\"800\" height=\"442\" class=\"aligncenter size-full\" \/><\/p>\n<li>Pulsa el <strong>\u00edcono de informe<\/strong> en la esquina superior derecha de la ventana, por encima de la barra de herramientas<\/li>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bulldozair.com\/wp-content\/uploads\/2020\/09\/sup-create-reports-2-android-en.png\" alt=\"\" width=\"800\" height=\"442\" class=\"aligncenter size-full\" \/><\/p>\n<li>Marca las casillas que corresponden a las notas que deseas incluir en tu informe<\/li>\n<li>Pulsa el <strong>\u00edcono de la flecha hacia arriba<\/strong> en la esquina inferior derecha de la aplicaci\u00f3n<\/li>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bulldozair.com\/wp-content\/uploads\/2020\/09\/sup-create-reports-3-android-en.png\" alt=\"\" width=\"800\" height=\"442\" class=\"aligncenter size-full\" \/><\/p>\n<li>BulldozAIR sincronizar\u00e1 tus archivos antes de generar el informe<\/li>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bulldozair.com\/wp-content\/uploads\/2020\/09\/sup-create-reports-4-android-en.png\" alt=\"\" width=\"800\" height=\"442\" class=\"aligncenter size-full\" \/><\/p>\n<li>Selecciona los par\u00e1metros adecuados para tu informe<\/li>\n<li>Pulsa el <strong>\u00edcono \u201c+\u201d<\/strong> en la esquina inferior derecha de la aplicaci\u00f3n<\/li>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bulldozair.com\/wp-content\/uploads\/2020\/09\/sup-create-reports-5-android-en.png\" alt=\"\" width=\"800\" height=\"442\" class=\"aligncenter size-full\" \/><\/p>\n<li>Acabas de generar tu informe. Pronto recibir\u00e1s un correo electr\u00f3nico de BulldozAIR conteniendo tu nuevo informe.<\/li>\n<\/ol><\/div>\n<div id=\"tabs-2\">\n<ol>\n<li>Seleccione el proyecto que contiene la nota desde la que se generar\u00e1 el informe<\/li>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bulldozair.com\/wp-content\/uploads\/2020\/09\/sup-create-reports-1-ios-en.png\" alt=\"\" width=\"800\" height=\"442\" class=\"aligncenter size-full\" \/><\/p>\n<li>Pulsa <strong>\u201cInforme\u201d<\/strong><\/li>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bulldozair.com\/wp-content\/uploads\/2020\/09\/sup-create-reports-2-ios-en.png\" alt=\"\" width=\"800\" height=\"442\" class=\"aligncenter size-full\" \/><\/p>\n<li>Marca las casillas que corresponden a las notas que deseas incluir en tu informe o utiliza los \u00edconos de la barra de b\u00fasqueda para filtrar las notas antes de seleccionar las que deseas incluir en tu informe.<\/li>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bulldozair.com\/wp-content\/uploads\/2020\/09\/sup-create-reports-3-ios-en.png\" alt=\"\" width=\"800\" height=\"442\" class=\"aligncenter size-full\" \/><\/p>\n<li>Pulsa <strong>\u201cExportar todo\u201d<\/strong> en la esquina superior derecha de la aplicaci\u00f3n<\/li>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bulldozair.com\/wp-content\/uploads\/2020\/09\/sup-create-reports-4-ios-en.png\" alt=\"\" width=\"800\" height=\"442\" class=\"aligncenter size-full\" \/><\/p>\n<li>Elige el tipo de informe que deseas exportar (<strong>Completo<\/strong>, <strong>Resumen<\/strong> o <strong>CSV para Excel<\/strong>)<\/li>\n<li>Dependiendo del tipo de informe, distintos par\u00e1metros aparecer\u00e1n. Selecciona las opciones dependiendo de tus preferencias y luego pulsa <strong>\u201cOK\u201d<\/strong><\/li>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bulldozair.com\/wp-content\/uploads\/2020\/09\/sup-create-reports-5-ios-en.png\" alt=\"\" width=\"800\" height=\"442\" class=\"aligncenter size-full\" \/><\/p>\n<li>Aparecer\u00e1 un mensaje comunic\u00e1ndote que tus datos se sincronizar\u00e1n antes de generar el informe, para continuar con el proceso pulsa <strong>\u201cOK\u201d<\/strong><\/li>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bulldozair.com\/wp-content\/uploads\/2020\/09\/sup-create-reports-6-ios-en.png\" alt=\"\" width=\"800\" height=\"442\" class=\"aligncenter size-full\" \/><\/p>\n<li>Ahora has generado tu informe, solo toca <strong>\u201cOK\u201d<\/strong> en el nuevo mensaje emergente comunic\u00e1ndote que pronto recibir\u00e1s un correo electr\u00f3nico de BulldozAIR con tu nuevo informe.<\/li>\n<\/ol><\/div>\n<div id=\"tabs-3\">\n<ol>\n<li>Seleccione el proyecto que contiene la nota desde la que se generar\u00e1 el informe<\/li>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bulldozair.com\/wp-content\/uploads\/2020\/09\/sup-create-reports-1-web-en.png\" alt=\"\" width=\"800\" height=\"442\" class=\"aligncenter size-full\" \/><\/p>\n<li>Puedes seleccionar manualmente tus notas marcando el c\u00edrculo en la esquina superior derecha de las notas<\/li>\n<li>Haz clic en <strong>\u201cExportar (# nota(s))\u201d<\/strong> en el extremo derecho de la barra de herramientas superior<\/li>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bulldozair.com\/wp-content\/uploads\/2020\/09\/sup-create-reports-2-web-en.png\" alt=\"\" width=\"800\" height=\"442\" class=\"aligncenter size-full\" \/><\/p>\n<li>Tambi\u00e9n puedes filtrar tus notas, primero haciendo clic en <strong>\u201cFiltros\u201d<\/strong>, luego escogiendo los criterios deseados en el men\u00fa del lado derecho para filtrarlas y finalmente seleccionando <strong>\u201cExportar\u201d<\/strong> en la parte inferior<\/li>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bulldozair.com\/wp-content\/uploads\/2020\/09\/sup-create-reports-3-web-en.png\" alt=\"\" width=\"800\" height=\"442\" class=\"aligncenter size-full\" \/><\/p>\n<li>Ahora, puedes elegir los par\u00e1metros para generar tu informe simplemente haciendo clic en las opciones disponibles (tipo de documento, organizaci\u00f3n de la informaci\u00f3n, etc.)<\/li>\n<li>Despu\u00e9s de seleccionar todos los par\u00e1metros, haz clic en <strong>\u00abGenerar informe\u00bb<\/strong> en la esquina inferior derecha de la ventana<\/li>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bulldozair.com\/wp-content\/uploads\/2020\/09\/sup-create-reports-4-web-en.png\" alt=\"\" width=\"800\" height=\"442\" class=\"aligncenter size-full\" \/><\/p>\n<li>Ser\u00e1s redirigido(a) a la secci\u00f3n <strong>\u201cINFORMES\u201d<\/strong> donde podr\u00e1s visualizar el informe que acabas de generar. Si no puedes acceder de inmediato a tu informe, espera unos segundos mientras el proceso finaliza.<\/li>\n<\/ol><\/div>\n<\/div>\n<p>Pasa menos tiempo frente a la computadora utilizando los informes automatizados de BulldozAIR y haz tu vida m\u00e1s f\u00e1cil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los informes son una herramienta informativa muy importante para ti y todos los dem\u00e1s colaboradores del proyecto, ya que te permiten resumir y mostrar de manera organizada toda la informaci\u00f3n de tus notas que consideres relevante. Existen tres tipos diferentes de informes: Resumen, Completo y CSV para Excel. Puedes escoger la informaci\u00f3n presente dentro de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[41],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Crea informes - Mezzoteam<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bulldozair.com\/es\/centro-ayuda\/sinc-busca-reporte\/crea-informes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crea informes - Mezzoteam\" \/>\n<meta property=\"og:description\" content=\"Los informes son una herramienta informativa muy importante para ti y todos los dem\u00e1s colaboradores del proyecto, ya que te permiten resumir y mostrar de manera organizada toda la informaci\u00f3n de tus notas que consideres relevante. Existen tres tipos diferentes de informes: Resumen, Completo y CSV para Excel. Puedes escoger la informaci\u00f3n presente dentro de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bulldozair.com\/es\/centro-ayuda\/sinc-busca-reporte\/crea-informes\/\" \/>\n<meta property=\"og:site_name\" content=\"Mezzoteam\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-18T23:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bulldozair.com\/wp-content\/uploads\/2020\/09\/sup-create-reports-1-android-en.png\" \/>\n<meta name=\"author\" content=\"Ali\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ali\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bulldozair.com\/es\/centro-ayuda\/sinc-busca-reporte\/crea-informes\/\",\"url\":\"https:\/\/www.bulldozair.com\/es\/centro-ayuda\/sinc-busca-reporte\/crea-informes\/\",\"name\":\"Crea informes - Mezzoteam\",\"isPartOf\":{\"@id\":\"https:\/\/www.bulldozair.com\/#website\"},\"datePublished\":\"2017-02-18T23:00:00+00:00\",\"dateModified\":\"2017-02-18T23:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.bulldozair.com\/#\/schema\/person\/831f13714e6b0e751f8383ef02ad62c5\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.bulldozair.com\/es\/centro-ayuda\/sinc-busca-reporte\/crea-informes\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bulldozair.com\/es\/centro-ayuda\/sinc-busca-reporte\/crea-informes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bulldozair.com\/es\/centro-ayuda\/sinc-busca-reporte\/crea-informes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Centro de Ayuda &amp; Formaci\u00f3n\",\"item\":\"https:\/\/www.bulldozair.com\/es\/centro-ayuda\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sincroniza, busca y crea reportes\",\"item\":\"https:\/\/www.bulldozair.com\/es\/centro-ayuda\/sinc-busca-reporte\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Crea informes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bulldozair.com\/#website\",\"url\":\"https:\/\/www.bulldozair.com\/\",\"name\":\"Mezzoteam\",\"description\":\"Construction project management software - Suivi de chantier\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bulldozair.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bulldozair.com\/#\/schema\/person\/831f13714e6b0e751f8383ef02ad62c5\",\"name\":\"Ali\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.bulldozair.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2865839485bc67b05b49d4ba604f8c7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2865839485bc67b05b49d4ba604f8c7?s=96&d=mm&r=g\",\"caption\":\"Ali\"},\"url\":\"https:\/\/www.bulldozair.com\/es\/author\/ali\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crea informes - Mezzoteam","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bulldozair.com\/es\/centro-ayuda\/sinc-busca-reporte\/crea-informes\/","og_locale":"es_ES","og_type":"article","og_title":"Crea informes - Mezzoteam","og_description":"Los informes son una herramienta informativa muy importante para ti y todos los dem\u00e1s colaboradores del proyecto, ya que te permiten resumir y mostrar de manera organizada toda la informaci\u00f3n de tus notas que consideres relevante. Existen tres tipos diferentes de informes: Resumen, Completo y CSV para Excel. Puedes escoger la informaci\u00f3n presente dentro de [&hellip;]","og_url":"https:\/\/www.bulldozair.com\/es\/centro-ayuda\/sinc-busca-reporte\/crea-informes\/","og_site_name":"Mezzoteam","article_published_time":"2017-02-18T23:00:00+00:00","og_image":[{"url":"https:\/\/www.bulldozair.com\/wp-content\/uploads\/2020\/09\/sup-create-reports-1-android-en.png"}],"author":"Ali","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ali","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bulldozair.com\/es\/centro-ayuda\/sinc-busca-reporte\/crea-informes\/","url":"https:\/\/www.bulldozair.com\/es\/centro-ayuda\/sinc-busca-reporte\/crea-informes\/","name":"Crea informes - Mezzoteam","isPartOf":{"@id":"https:\/\/www.bulldozair.com\/#website"},"datePublished":"2017-02-18T23:00:00+00:00","dateModified":"2017-02-18T23:00:00+00:00","author":{"@id":"https:\/\/www.bulldozair.com\/#\/schema\/person\/831f13714e6b0e751f8383ef02ad62c5"},"breadcrumb":{"@id":"https:\/\/www.bulldozair.com\/es\/centro-ayuda\/sinc-busca-reporte\/crea-informes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bulldozair.com\/es\/centro-ayuda\/sinc-busca-reporte\/crea-informes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bulldozair.com\/es\/centro-ayuda\/sinc-busca-reporte\/crea-informes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Centro de Ayuda &amp; Formaci\u00f3n","item":"https:\/\/www.bulldozair.com\/es\/centro-ayuda\/"},{"@type":"ListItem","position":2,"name":"Sincroniza, busca y crea reportes","item":"https:\/\/www.bulldozair.com\/es\/centro-ayuda\/sinc-busca-reporte\/"},{"@type":"ListItem","position":3,"name":"Crea informes"}]},{"@type":"WebSite","@id":"https:\/\/www.bulldozair.com\/#website","url":"https:\/\/www.bulldozair.com\/","name":"Mezzoteam","description":"Construction project management software - Suivi de chantier","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bulldozair.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.bulldozair.com\/#\/schema\/person\/831f13714e6b0e751f8383ef02ad62c5","name":"Ali","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bulldozair.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2865839485bc67b05b49d4ba604f8c7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2865839485bc67b05b49d4ba604f8c7?s=96&d=mm&r=g","caption":"Ali"},"url":"https:\/\/www.bulldozair.com\/es\/author\/ali\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bulldozair.com\/es\/wp-json\/wp\/v2\/posts\/2421"}],"collection":[{"href":"https:\/\/www.bulldozair.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bulldozair.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bulldozair.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bulldozair.com\/es\/wp-json\/wp\/v2\/comments?post=2421"}],"version-history":[{"count":0,"href":"https:\/\/www.bulldozair.com\/es\/wp-json\/wp\/v2\/posts\/2421\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.bulldozair.com\/es\/wp-json\/wp\/v2\/media?parent=2421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bulldozair.com\/es\/wp-json\/wp\/v2\/categories?post=2421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bulldozair.com\/es\/wp-json\/wp\/v2\/tags?post=2421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}